{"id":4093,"date":"2013-08-19T16:50:04","date_gmt":"2013-08-19T14:50:04","guid":{"rendered":"https:\/\/www.sazolene.it\/fr\/come-funziona\/come-utilizzare-sazolene\/"},"modified":"2016-09-29T15:15:01","modified_gmt":"2016-09-29T13:15:01","slug":"comment-utiliser-sazolene","status":"publish","type":"page","link":"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/","title":{"rendered":"COMMENT UTILISER SAZOLENE\u00ae?"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":4090,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4093","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COMMENT UTILISER SAZOLENE\u00ae? | Sazolene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMMENT UTILISER SAZOLENE\u00ae? | Sazolene\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/\" \/>\n<meta property=\"og:site_name\" content=\"Sazolene\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-29T13:15:01+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/\",\"url\":\"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/\",\"name\":\"COMMENT UTILISER SAZOLENE\u00ae? | Sazolene\",\"isPartOf\":{\"@id\":\"https:\/\/www.sazolene.it\/ja\/#website\"},\"datePublished\":\"2013-08-19T14:50:04+00:00\",\"dateModified\":\"2016-09-29T13:15:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sazolene.it\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment l&rsquo;engrais Sazolene\u00ae fonctionnne-t-il\",\"item\":\"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COMMENT UTILISER SAZOLENE\u00ae?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sazolene.it\/ja\/#website\",\"url\":\"https:\/\/www.sazolene.it\/ja\/\",\"name\":\"Sazolene\",\"description\":\"Fertilizzante azotato a lento rilascio\",\"publisher\":{\"@id\":\"https:\/\/www.sazolene.it\/ja\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sazolene.it\/ja\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sazolene.it\/ja\/#organization\",\"name\":\"Sazolene\",\"url\":\"https:\/\/www.sazolene.it\/ja\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sazolene.it\/ja\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sazolene.it\/wp-content\/uploads\/2020\/02\/logosazolene1.png\",\"contentUrl\":\"https:\/\/www.sazolene.it\/wp-content\/uploads\/2020\/02\/logosazolene1.png\",\"width\":209,\"height\":97,\"caption\":\"Sazolene\"},\"image\":{\"@id\":\"https:\/\/www.sazolene.it\/ja\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMMENT UTILISER SAZOLENE\u00ae? | Sazolene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/","og_locale":"fr_FR","og_type":"article","og_title":"COMMENT UTILISER SAZOLENE\u00ae? | Sazolene","og_url":"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/","og_site_name":"Sazolene","article_modified_time":"2016-09-29T13:15:01+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/","url":"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/","name":"COMMENT UTILISER SAZOLENE\u00ae? | Sazolene","isPartOf":{"@id":"https:\/\/www.sazolene.it\/ja\/#website"},"datePublished":"2013-08-19T14:50:04+00:00","dateModified":"2016-09-29T13:15:01+00:00","breadcrumb":{"@id":"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/comment-utiliser-sazolene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sazolene.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment l&rsquo;engrais Sazolene\u00ae fonctionnne-t-il","item":"https:\/\/www.sazolene.it\/fr\/comment-lengrais-sazolene-fonctionne-t-il\/"},{"@type":"ListItem","position":3,"name":"COMMENT UTILISER SAZOLENE\u00ae?"}]},{"@type":"WebSite","@id":"https:\/\/www.sazolene.it\/ja\/#website","url":"https:\/\/www.sazolene.it\/ja\/","name":"Sazolene","description":"Fertilizzante azotato a lento rilascio","publisher":{"@id":"https:\/\/www.sazolene.it\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sazolene.it\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.sazolene.it\/ja\/#organization","name":"Sazolene","url":"https:\/\/www.sazolene.it\/ja\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sazolene.it\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/www.sazolene.it\/wp-content\/uploads\/2020\/02\/logosazolene1.png","contentUrl":"https:\/\/www.sazolene.it\/wp-content\/uploads\/2020\/02\/logosazolene1.png","width":209,"height":97,"caption":"Sazolene"},"image":{"@id":"https:\/\/www.sazolene.it\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/pages\/4093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/comments?post=4093"}],"version-history":[{"count":1,"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/pages\/4093\/revisions"}],"predecessor-version":[{"id":4094,"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/pages\/4093\/revisions\/4094"}],"up":[{"embeddable":true,"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/pages\/4090"}],"wp:attachment":[{"href":"https:\/\/www.sazolene.it\/fr\/wp-json\/wp\/v2\/media?parent=4093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}